{"id":41872,"date":"2026-05-27T10:22:55","date_gmt":"2026-05-27T08:22:55","guid":{"rendered":"https:\/\/staging.sebworld-auktionen.de\/produkt\/juego-de-3-sillas-pb-2"},"modified":"2026-05-29T16:11:59","modified_gmt":"2026-05-29T14:11:59","slug":"juego-de-3-sillas-pb-2","status":"publish","type":"product","link":"https:\/\/staging.sebworld-auktionen.de\/es\/lotes\/juego-de-3-sillas-pb-2","title":{"rendered":"Juego de 3 sillas P&#038;B"},"content":{"rendered":"<p>Conjunto de 3 | Pl\u00e1stico | Rojo | Madera de Marco | H: 84cm | SH: 48cm | An: 49cm | T: aprox. 60 cm<\/p>\n<p style=\"font-weight: 400;\">*Visualizaci\u00f3n y recogida: Redcarstr. 3, 53842 Troisdorf* <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conjunto de 3 | Pl\u00e1stico | Rojo | Madera de Marco | H: 84cm | SH: 48cm | An: 49cm | T: aprox. 60 cm *Visualizaci\u00f3n y recogida: Redcarstr. 3, 53842 Troisdorf*<\/p>\n","protected":false},"featured_media":41873,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[242],"product_tag":[],"class_list":["post-41872","product","type-product","status-publish","has-post-thumbnail","product_cat-sillas-de-visitantes","first","outofstock","taxable","shipping-taxable","product-type-auction"],"acf":[],"_links":{"self":[{"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/product\/41872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/media\/41873"}],"wp:attachment":[{"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/media?parent=41872"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/product_brand?post=41872"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/product_cat?post=41872"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/product_tag?post=41872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}