{"id":32596,"date":"2026-05-11T11:16:21","date_gmt":"2026-05-11T09:16:21","guid":{"rendered":"https:\/\/staging.sebworld-auktionen.de\/produkt\/reiss-electr-escritorio-con-ajuste-de-altura-4"},"modified":"2026-05-22T17:19:29","modified_gmt":"2026-05-22T15:19:29","slug":"reiss-electr-escritorio-con-ajuste-de-altura-4","status":"publish","type":"product","link":"https:\/\/staging.sebworld-auktionen.de\/es\/lotes\/reiss-electr-escritorio-con-ajuste-de-altura-4","title":{"rendered":"Reiss electr. Escritorio con ajuste de altura"},"content":{"rendered":"<p>Resina sint\u00e9tica | Blanco | Ajustable el\u00e9ctricamente en altura | Enchufe de cable 4x | H: 69-125cm | An: 180cm | T: 90cm<\/p>\n<p>*Las fotos son ejemplares | Todos los escritorios Reiss son id\u00e9nticos*<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resina sint\u00e9tica | Blanco | Ajustable el\u00e9ctricamente en altura | Enchufe de cable 4x | H: 69-125cm | An: 180cm | T: 90cm *Las fotos son ejemplares | Todos los escritorios Reiss son id\u00e9nticos*<\/p>\n","protected":false},"featured_media":26243,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[238,264],"product_tag":[],"class_list":["post-32596","product","type-product","status-publish","has-post-thumbnail","product_cat-escritorios","product_cat-tablas","first","outofstock","taxable","shipping-taxable","product-type-auction"],"acf":[],"_links":{"self":[{"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/product\/32596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/media\/26243"}],"wp:attachment":[{"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/media?parent=32596"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/product_brand?post=32596"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/product_cat?post=32596"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/product_tag?post=32596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}