{"id":32516,"date":"2026-05-07T17:06:48","date_gmt":"2026-05-07T15:06:48","guid":{"rendered":"https:\/\/staging.sebworld-auktionen.de\/produkt\/rexite-cactus-plastico-negro-de-acero-4"},"modified":"2026-05-22T17:24:46","modified_gmt":"2026-05-22T15:24:46","slug":"rexite-cactus-plastico-negro-de-acero-4","status":"publish","type":"product","link":"https:\/\/staging.sebworld-auktionen.de\/es\/lotes\/rexite-cactus-plastico-negro-de-acero-4","title":{"rendered":"Rexite Cactus Pl\u00e1stico \/ Negro de acero"},"content":{"rendered":"<p>Pl\u00e1stico \/ Acero | Negro | 8x ganchos para abrigos | con soporte para paraguas | H: 167cm | \u00d8: 40cm<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pl\u00e1stico \/ Acero | Negro | 8x ganchos para abrigos | con soporte para paraguas | H: 167cm | \u00d8: 40cm<\/p>\n","protected":false},"featured_media":26153,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[271],"product_tag":[],"class_list":["post-32516","product","type-product","status-publish","has-post-thumbnail","product_cat-guardarropas","first","outofstock","taxable","shipping-taxable","product-type-auction"],"acf":[],"_links":{"self":[{"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/product\/32516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/media\/26153"}],"wp:attachment":[{"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/media?parent=32516"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/product_brand?post=32516"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/product_cat?post=32516"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/product_tag?post=32516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}