{"id":23528,"date":"2026-04-13T15:26:45","date_gmt":"2026-04-13T13:26:45","guid":{"rendered":"https:\/\/staging.sebworld-auktionen.de\/produkt\/maniqui-sentado-en-plastico-blanco-sin-silla-2"},"modified":"2026-04-13T15:26:45","modified_gmt":"2026-04-13T13:26:45","slug":"maniqui-sentado-en-plastico-blanco-sin-silla-2","status":"publish","type":"product","link":"https:\/\/staging.sebworld-auktionen.de\/es\/lotes\/maniqui-sentado-en-plastico-blanco-sin-silla-2","title":{"rendered":"Maniqu\u00ed sentado en pl\u00e1stico blanco (\u00a1sin silla!)"},"content":{"rendered":"<p>Maniqu\u00ed sin silla | Pl\u00e1stico | Blanco | Se pueden quitar brazos, piernas\/manos | H: aprox. 132cm<\/p>\n<p>*Visualizaci\u00f3n y recogida: Redcarstr. 3, 53842 Troisdorf* <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Maniqu\u00ed sin silla | Pl\u00e1stico | Blanco | Se pueden quitar brazos, piernas\/manos | H: aprox. 132cm *Visualizaci\u00f3n y recogida: Redcarstr. 3, 53842 Troisdorf*<\/p>\n","protected":false},"featured_media":13774,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[252],"product_tag":[],"class_list":["post-23528","product","type-product","status-publish","has-post-thumbnail","product_cat-condecoracion","first","outofstock","taxable","shipping-taxable","product-type-auction"],"acf":[],"_links":{"self":[{"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/product\/23528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/media\/13774"}],"wp:attachment":[{"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/media?parent=23528"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/product_brand?post=23528"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/product_cat?post=23528"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/staging.sebworld-auktionen.de\/es\/wp-json\/wp\/v2\/product_tag?post=23528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}